{"id":12,"date":"2025-10-22T18:24:54","date_gmt":"2025-10-22T18:24:54","guid":{"rendered":"https:\/\/biocure-bd.com\/wordpress\/?page_id=12"},"modified":"2026-06-29T09:07:42","modified_gmt":"2026-06-29T09:07:42","slug":"home","status":"publish","type":"page","link":"https:\/\/biocure-bd.com\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12\" class=\"elementor elementor-12\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8e3854 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"d8e3854\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9071e21 elementor-widget elementor-widget-heading\" data-id=\"9071e21\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Science of Wellness, Realized.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-896f95d elementor-widget elementor-widget-spacer\" data-id=\"896f95d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b84e50 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6b84e50\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/biocure-bd.com\/index.php\/about\/\" id=\"learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#043252\" stroke=\"#043252\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce1f2c5 e-flex e-con-boxed e-con e-parent\" data-id=\"ce1f2c5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51c2284 elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"51c2284\" data-element_type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;2b31760&quot;}],&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:10000,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 1\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77d4ffd e-con-full e-flex e-con e-child\" data-id=\"77d4ffd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/vimeo.com\\\/1129830611?share=copy&amp;fl=sv&amp;fe=ci&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-background-video-container\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\"><\/div>\n\t\t\t\t\t\t<\/div><div class=\"elementor-element elementor-element-3449962 e-con-full e-flex e-con e-child\" data-id=\"3449962\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/vimeo.com\\\/1129830611?fl=ip&amp;fe=ec&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-background-video-container\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\"><\/div>\n\t\t\t\t\t\t<\/div><div class=\"elementor-element elementor-element-92bf11a e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"92bf11a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6feb4b9 elementor-widget elementor-widget-heading\" data-id=\"6feb4b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BIOCURE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59722b4 elementor-widget elementor-widget-heading\" data-id=\"59722b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Science of<br>Wellness, Realized.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df5687f elementor-widget elementor-widget-spacer\" data-id=\"df5687f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11f40e4 elementor-widget elementor-widget-button\" data-id=\"11f40e4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/biocure-bd.com\/index.php\/about\/\" id=\"learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#043252\" stroke=\"#043252\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46b52cd e-flex e-con-boxed e-con e-parent\" data-id=\"46b52cd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-04f3ea2 e-con-full e-flex e-con e-child\" data-id=\"04f3ea2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-707a1c6 elementor-widget elementor-widget-image\" data-id=\"707a1c6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"648\" height=\"512\" src=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/10\/mask-man.jpg\" class=\"attachment-full size-full wp-image-236\" alt=\"\" srcset=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/10\/mask-man.jpg 648w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/10\/mask-man-300x237.jpg 300w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baa20d9 elementor-position-left elementor-widget__width-initial elementor-mobile-position-left elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"baa20d9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><path d=\"M0 24C0 10.7452 10.7452 0 24 0C37.2548 0 48 10.7452 48 24C48 37.2548 37.2548 48 24 48C10.7452 48 0 37.2548 0 24Z\" fill=\"#F4F9EC\"><\/path><path d=\"M21 24L23 26L27 22M33 24C33 25.1819 32.7672 26.3522 32.3149 27.4442C31.8626 28.5361 31.1997 29.5282 30.364 30.364C29.5282 31.1997 28.5361 31.8626 27.4442 32.3149C26.3522 32.7672 25.1819 33 24 33C22.8181 33 21.6478 32.7672 20.5558 32.3149C19.4639 31.8626 18.4718 31.1997 17.636 30.364C16.8003 29.5282 16.1374 28.5361 15.6851 27.4442C15.2328 26.3522 15 25.1819 15 24C15 21.6131 15.9482 19.3239 17.636 17.636C19.3239 15.9482 21.6131 15 24 15C26.3869 15 28.6761 15.9482 30.364 17.636C32.0518 19.3239 33 21.6131 33 24Z\" stroke=\"#8CB93F\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWHO-GMP Verified\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInternational Quality Standards\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0749e19 e-con-full e-flex e-con e-child\" data-id=\"0749e19\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6e3e6b elementor-widget elementor-widget-heading\" data-id=\"e6e3e6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About BIOCURE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee783a1 elementor-widget elementor-widget-spacer\" data-id=\"ee783a1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3f571f elementor-widget elementor-widget-text-editor\" data-id=\"f3f571f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>BIOCURE is a leading pharma company in Bangladesh, dedicated to improving healthcare through innovative and high-quality pharmaceutical products. With state-of-the-art manufacturing facilities and a commitment to excellence, we serve millions of patients across the country.<\/p><p>Our mission is to provide affordable, accessible, and effective healthcare solutions while maintaining the highest standards of quality and safety. We are committed to research and development, continuously innovating to meet the evolving healthcare needs of our community.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94378b1 elementor-widget elementor-widget-spacer\" data-id=\"94378b1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea86971 e-grid e-con-full e-con e-child\" data-id=\"ea86971\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ded47b4 elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"ded47b4\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path d=\"M17 26H9C7.346 26 6 24.654 6 23V6C6 4.346 7.346 3 9 3H21C22.654 3 24 4.346 24 6V11.06C24 11.3252 24.1054 11.5796 24.2929 11.7671C24.4804 11.9546 24.7348 12.06 25 12.06C25.2652 12.06 25.5196 11.9546 25.7071 11.7671C25.8946 11.5796 26 11.3252 26 11.06V6C26 3.243 23.757 1 21 1H9C6.243 1 4 3.243 4 6V23C4 25.757 6.243 28 9 28H17C17.2652 28 17.5196 27.8946 17.7071 27.7071C17.8946 27.5196 18 27.2652 18 27C18 26.7348 17.8946 26.4804 17.7071 26.2929C17.5196 26.1054 17.2652 26 17 26Z\" fill=\"#8CB93F\"><\/path><path d=\"M10 9H17C17.2652 9 17.5196 8.89464 17.7071 8.70711C17.8946 8.51957 18 8.26522 18 8C18 7.73478 17.8946 7.48043 17.7071 7.29289C17.5196 7.10536 17.2652 7 17 7H10C9.73478 7 9.48043 7.10536 9.29289 7.29289C9.10536 7.48043 9 7.73478 9 8C9 8.26522 9.10536 8.51957 9.29289 8.70711C9.48043 8.89464 9.73478 9 10 9ZM19.36 13C19.36 12.7348 19.2546 12.4804 19.0671 12.2929C18.8796 12.1054 18.6252 12 18.36 12H10C9.73478 12 9.48043 12.1054 9.29289 12.2929C9.10536 12.4804 9 12.7348 9 13C9 13.2652 9.10536 13.5196 9.29289 13.7071C9.48043 13.8946 9.73478 14 10 14H18.36C18.6252 14 18.8796 13.8946 19.0671 13.7071C19.2546 13.5196 19.36 13.2652 19.36 13ZM16.52 17C16.52 16.7348 16.4146 16.4804 16.2271 16.2929C16.0396 16.1054 15.7852 16 15.52 16H10C9.73478 16 9.48043 16.1054 9.29289 16.2929C9.10536 16.4804 9 16.7348 9 17C9 17.2652 9.10536 17.5196 9.29289 17.7071C9.48043 17.8946 9.73478 18 10 18H15.52C15.7852 18 16.0396 17.8946 16.2271 17.7071C16.4146 17.5196 16.52 17.2652 16.52 17ZM10 20C9.73478 20 9.48043 20.1054 9.29289 20.2929C9.10536 20.4804 9 20.7348 9 21C9 21.2652 9.10536 21.5196 9.29289 21.7071C9.48043 21.8946 9.73478 22 10 22H15.06C15.3252 22 15.5796 21.8946 15.7671 21.7071C15.9546 21.5196 16.06 21.2652 16.06 21C16.06 20.7348 15.9546 20.4804 15.7671 20.2929C15.5796 20.1054 15.3252 20 15.06 20H10ZM30 20C30 16.691 27.309 14 24 14C20.691 14 18 16.691 18 20C18 21.771 18.776 23.36 20 24.46V29.497C20 30.051 20.305 30.559 20.794 30.821C21.286 31.085 21.874 31.056 22.338 30.747L24 29.631L25.666 30.749C25.8928 30.8979 26.1555 30.9828 26.4266 30.9947C26.6976 31.0067 26.9668 30.9453 27.2058 30.817C27.4448 30.6887 27.6448 30.4982 27.7846 30.2657C27.9243 30.0332 27.9988 29.7673 28 29.496V24.459C28.6287 23.8984 29.1318 23.2113 29.4765 22.4427C29.8212 21.6741 29.9996 20.8423 30 20ZM26 28.564L24.558 27.596C24.3932 27.485 24.1991 27.4258 24.0005 27.4258C23.8019 27.4258 23.6078 27.485 23.443 27.596L22.001 28.564V25.65C22.628 25.873 23.299 26 24.001 26C24.703 26 25.374 25.872 26.001 25.65L26 28.564ZM24 24C21.794 24 20 22.206 20 20C20 17.794 21.794 16 24 16C26.206 16 28 17.794 28 20C28 22.206 26.206 24 24 24Z\" fill=\"#8CB93F\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t25+\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tYears Experience\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb92e1 elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"3bb92e1\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path d=\"M20.4064 12.8C21.9536 12.8 23.2064 14.0528 23.2064 15.6V23.1984C23.2064 25.1084 22.4477 26.9401 21.0971 28.2907C19.7465 29.6412 17.9148 30.4 16.0048 30.4C14.0948 30.4 12.2631 29.6412 10.9125 28.2907C9.56194 26.9401 8.8032 25.1084 8.8032 23.1984V15.6C8.8032 14.0528 10.056 12.8 11.6032 12.8H20.4064ZM20.4064 15.2H11.6032C11.4971 15.2 11.3954 15.2421 11.3204 15.3171C11.2453 15.3921 11.2032 15.4939 11.2032 15.6V23.1984C11.2032 24.4718 11.7091 25.6931 12.6096 26.5936C13.51 27.4941 14.7313 28 16.0048 28C17.2783 28 18.4996 27.4941 19.4 26.5936C20.3005 25.6931 20.8064 24.4718 20.8064 23.1984V15.6C20.8064 15.4939 20.7643 15.3921 20.6892 15.3171C20.6142 15.2421 20.5125 15.2 20.4064 15.2ZM2.8 12.8H8.2096C7.64512 13.4817 7.30038 14.3185 7.2208 15.2H2.8C2.69391 15.2 2.59217 15.2421 2.51716 15.3171C2.44214 15.3921 2.4 15.4939 2.4 15.6V20.7984C2.3999 21.403 2.5368 21.9998 2.80044 22.5439C3.06407 23.088 3.44757 23.5653 3.92213 23.9399C4.39669 24.3145 4.94998 24.5768 5.54043 24.7069C6.13087 24.837 6.74313 24.8316 7.3312 24.6912C7.4672 25.4976 7.7152 26.2672 8.056 26.9824C7.10765 27.2361 6.11365 27.2683 5.15087 27.0765C4.18809 26.8847 3.28232 26.474 2.5036 25.8762C1.72487 25.2785 1.09406 24.5096 0.659941 23.6291C0.22582 22.7486 1.96796e-05 21.7801 0 20.7984V15.6C0 14.0528 1.2544 12.8 2.8 12.8ZM23.8 12.8H29.2C30.7472 12.8 32 14.0528 32 15.6V20.8C32.0002 21.781 31.7749 22.749 31.3414 23.6291C30.908 24.5092 30.278 25.2779 29.5001 25.8758C28.7222 26.4736 27.8174 26.8846 26.8554 27.0771C25.8933 27.2695 24.9 27.2382 23.952 26.9856C24.2944 26.2688 24.5424 25.4992 24.68 24.6928C25.2673 24.8316 25.8785 24.8357 26.4676 24.7048C27.0568 24.5739 27.6087 24.3114 28.0819 23.9369C28.5552 23.5624 28.9377 23.0857 29.2006 22.5424C29.4634 21.9992 29.6 21.4035 29.6 20.8V15.6C29.6 15.4939 29.5579 15.3921 29.4828 15.3171C29.4078 15.2421 29.3061 15.2 29.2 15.2H24.7888C24.7092 14.3185 24.3645 13.4817 23.8 12.8ZM16 1.59998C17.273 1.59998 18.4939 2.10569 19.3941 3.00586C20.2943 3.90604 20.8 5.12694 20.8 6.39998C20.8 7.67301 20.2943 8.89391 19.3941 9.79409C18.4939 10.6943 17.273 11.2 16 11.2C14.727 11.2 13.5061 10.6943 12.6059 9.79409C11.7057 8.89391 11.2 7.67301 11.2 6.39998C11.2 5.12694 11.7057 3.90604 12.6059 3.00586C13.5061 2.10569 14.727 1.59998 16 1.59998ZM26.4 3.19998C27.4609 3.19998 28.4783 3.6214 29.2284 4.37155C29.9786 5.12169 30.4 6.13911 30.4 7.19998C30.4 8.26084 29.9786 9.27826 29.2284 10.0284C28.4783 10.7785 27.4609 11.2 26.4 11.2C25.3391 11.2 24.3217 10.7785 23.5716 10.0284C22.8214 9.27826 22.4 8.26084 22.4 7.19998C22.4 6.13911 22.8214 5.12169 23.5716 4.37155C24.3217 3.6214 25.3391 3.19998 26.4 3.19998ZM5.6 3.19998C6.66087 3.19998 7.67828 3.6214 8.42843 4.37155C9.17857 5.12169 9.6 6.13911 9.6 7.19998C9.6 8.26084 9.17857 9.27826 8.42843 10.0284C7.67828 10.7785 6.66087 11.2 5.6 11.2C4.53913 11.2 3.52172 10.7785 2.77157 10.0284C2.02143 9.27826 1.6 8.26084 1.6 7.19998C1.6 6.13911 2.02143 5.12169 2.77157 4.37155C3.52172 3.6214 4.53913 3.19998 5.6 3.19998ZM16 3.99998C15.3635 3.99998 14.753 4.25283 14.3029 4.70292C13.8529 5.15301 13.6 5.76346 13.6 6.39998C13.6 7.03649 13.8529 7.64694 14.3029 8.09703C14.753 8.54712 15.3635 8.79997 16 8.79998C16.6365 8.79998 17.247 8.54712 17.6971 8.09703C18.1471 7.64694 18.4 7.03649 18.4 6.39998C18.4 5.76346 18.1471 5.15301 17.6971 4.70292C17.247 4.25283 16.6365 3.99998 16 3.99998ZM26.4 5.59998C25.9757 5.59998 25.5687 5.76855 25.2686 6.0686C24.9686 6.36866 24.8 6.77563 24.8 7.19998C24.8 7.62432 24.9686 8.03129 25.2686 8.33135C25.5687 8.6314 25.9757 8.79998 26.4 8.79998C26.8243 8.79998 27.2313 8.6314 27.5314 8.33135C27.8314 8.03129 28 7.62432 28 7.19998C28 6.77563 27.8314 6.36866 27.5314 6.0686C27.2313 5.76855 26.8243 5.59998 26.4 5.59998ZM5.6 5.59998C5.17565 5.59998 4.76869 5.76855 4.46863 6.0686C4.16857 6.36866 4 6.77563 4 7.19998C4 7.62432 4.16857 8.03129 4.46863 8.33135C4.76869 8.6314 5.17565 8.79998 5.6 8.79998C6.02435 8.79998 6.43131 8.6314 6.73137 8.33135C7.03143 8.03129 7.2 7.62432 7.2 7.19998C7.2 6.77563 7.03143 6.36866 6.73137 6.0686C6.43131 5.76855 6.02435 5.59998 5.6 5.59998Z\" fill=\"#8CB93F\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t100+\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tExpert Team\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23193b8 elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"23193b8\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><g clip-path=\"url(#clip0_32_123)\"><path d=\"M29.1952 25.0392C30.9634 22.4659 32 19.3525 32 16.0011C32 7.178 24.8231 0 16.0011 0C12.7778 0 9.77456 0.958937 7.26013 2.60519C7.20249 2.63569 7.1479 2.67165 7.09713 2.71256C2.81994 5.58781 0 10.4712 0 16.0011C0 24.8231 7.178 32 16.0011 32C21.3926 32 26.1693 29.3192 29.0693 25.2208C29.1177 25.165 29.1599 25.1041 29.1952 25.0392ZM16.0011 29.9522C8.30731 29.9522 2.04787 23.6939 2.04787 16.0011C2.04787 11.5278 4.16431 7.53988 7.44794 4.98462C7.94269 5.5965 8.54431 5.98037 9.18594 6.07475C9.29906 6.09137 9.41338 6.09919 9.52875 6.09919C10.3147 6.09919 11.1395 5.73587 12.0076 5.35369C12.3431 5.20556 12.6937 5.05081 13.0542 4.91325C13.5823 4.71137 13.8474 4.1195 13.6455 3.5915C13.4442 3.06288 12.8523 2.79888 12.3237 3.00025C11.9305 3.15056 11.5477 3.31806 11.1817 3.4795C10.5604 3.75294 9.78506 4.08962 9.48438 4.04856C9.40112 4.03619 9.28875 3.9645 9.16638 3.84037C11.0981 2.75037 13.3135 2.10687 15.6722 2.052C15.4739 2.80975 15.2209 3.71888 14.9722 3.9825C14.6544 4.31862 14.0509 4.61369 13.519 4.87444C12.6421 5.30319 11.7358 5.74694 11.5261 6.65494C11.4451 7.0055 11.4473 7.55131 11.9204 8.15806C12.7508 9.22356 14.2434 9.253 15.6872 9.28181C16.4859 9.29731 17.3906 9.31506 17.8104 9.54419C17.9497 9.62019 18.0778 9.806 18.1305 10.0063C18.1737 10.171 18.1455 10.2653 18.1399 10.2764C18.1394 10.2769 18.1089 10.3008 18.0584 10.3136C17.9779 10.3047 17.7622 10.1993 17.6196 10.1294C17.3373 9.99187 17.0167 9.83494 16.6439 9.775C16.1431 9.694 15.6983 9.76 15.3404 9.81275C15.1402 9.84212 14.9804 9.86544 14.8085 9.86769C14.5295 9.86712 14.215 9.81169 13.8822 9.75288C13.1401 9.62144 12.2171 9.45837 11.2708 9.87988C10.3722 10.2798 9.6035 11.134 8.98612 11.8207C8.84025 11.9832 8.701 12.1379 8.56956 12.2761L8.44862 12.4025C7.05919 13.8552 6.05525 14.9046 7.26606 17.5681C7.9605 19.0951 8.67325 20.2633 10.9596 20.2633H10.9818C11.5981 20.261 12.1644 20.0985 12.6641 19.9554C12.8355 19.9061 13.0668 19.8395 13.2376 19.8057C13.2504 19.8917 13.2609 20.0137 13.2626 20.1817C13.2714 21.0576 13.8094 21.5501 14.1312 21.8441C14.2116 21.9184 14.3336 22.0299 14.3519 22.056C14.3519 22.056 14.3558 22.0904 14.3359 22.1731C14.2649 22.4654 14.1711 22.6085 14.053 22.7893C13.723 23.2952 13.4584 23.836 13.8261 24.8793L13.825 24.8804L13.8527 24.9542C13.8561 24.9631 13.8594 24.9719 13.8628 24.9814C13.865 24.9864 13.8666 24.9919 13.8689 24.9969C13.9476 25.2143 14.0236 25.536 14.1046 25.8766C14.3886 27.073 14.9522 29.4514 17.0144 29.4509C17.2086 29.4509 17.4166 29.4304 17.6401 29.3866C19.4234 29.0238 20.2488 26.9998 20.7946 25.6614C20.84 25.5495 20.8861 25.4378 20.9327 25.3264C21.6188 25.2321 22.1224 24.9808 22.4647 24.5671C23.0771 23.8238 22.9046 22.8919 22.7786 22.2108C22.7398 22.0017 22.6777 21.67 22.6871 21.5086C23.7504 21.0654 25.9269 20.148 25.5975 18.2183C25.4522 17.3619 24.6995 16.602 23.7471 15.6402C23.0072 14.8925 21.6305 13.5014 21.9056 12.9889C22.1736 12.4908 21.9866 11.8701 21.4885 11.6022C20.9915 11.3348 20.3697 11.5212 20.1018 12.0193C19.1095 13.8658 20.8739 15.6479 22.2916 17.0807C22.7714 17.5649 23.4969 18.2971 23.5784 18.5616C23.5918 18.6398 23.5086 18.9471 21.8795 19.6255C20.3359 20.2695 20.6248 21.832 20.7641 22.583C20.8007 22.7816 20.8584 23.0927 20.855 23.2558C20.7734 23.2819 20.6026 23.3185 20.2876 23.3213C20.1498 23.3225 20.0136 23.3514 19.8872 23.4064C19.7609 23.4614 19.6469 23.5413 19.5521 23.6413C19.2958 23.9114 19.1372 24.2997 18.8976 24.8882C18.5626 25.708 17.9402 27.2344 17.2307 27.3792C16.7837 27.4729 16.5274 27.2161 16.0981 25.4051C16.0094 25.0291 15.9245 24.6719 15.8147 24.3551L15.8158 24.3546L15.7892 24.2841C15.7861 24.2759 15.783 24.2678 15.7797 24.2597C15.7792 24.2574 15.7781 24.2547 15.7775 24.2525C15.7304 24.1277 15.7104 24.0512 15.7021 24.0096C15.7215 23.9768 15.7442 23.9457 15.7675 23.9108C15.9284 23.6634 16.1724 23.2912 16.3261 22.6561C16.6394 21.3632 15.879 20.6676 15.5135 20.3332C15.4369 20.2627 15.3133 20.1607 15.3105 20.1607C15.3038 19.5184 15.2134 18.6038 14.5046 18.0751C13.7513 17.5127 12.835 17.7751 12.0995 17.9864C11.7101 18.0979 11.3069 18.2132 10.9752 18.2144C9.88306 18.2049 9.70944 17.9919 9.13094 16.7196C8.49306 15.3179 8.60181 15.2042 9.92856 13.8176L10.0506 13.69C10.1953 13.5386 10.3484 13.3683 10.5087 13.1903C10.9963 12.6483 11.6026 11.9733 12.1029 11.7509C12.4595 11.5923 12.8755 11.6544 13.5256 11.7692C13.9117 11.8369 14.3482 11.9145 14.8047 11.9151C15.1036 11.9151 15.3926 11.8746 15.6384 11.8385C15.9018 11.7991 16.1292 11.7648 16.3173 11.7964C16.3905 11.808 16.5886 11.9051 16.7194 11.9694C17.1304 12.1702 17.6912 12.4437 18.3468 12.3372C19.328 12.1758 20.0086 11.5185 20.1678 10.5794C20.3519 9.49231 19.7601 8.27425 18.7906 7.74619C17.9314 7.27863 16.8115 7.25644 15.7282 7.23481C15.1519 7.22319 14.27 7.206 13.7924 7.034C13.9894 6.92419 14.2312 6.806 14.4192 6.71394C15.1081 6.37669 15.8891 5.99456 16.4609 5.38825C17.0988 4.71375 17.3989 3.55337 17.7173 2.32481L17.7605 2.15862C23.754 2.91625 28.5736 7.49206 29.7013 13.3647C29.6145 13.3239 29.5105 13.271 29.3836 13.2036C28.8683 12.929 28.1634 12.5541 27.3507 12.8242C26.572 13.0837 26.2791 13.7999 26.1049 14.2286C25.6712 13.9247 24.8109 13.0716 24.1803 12.3666C23.8031 11.9451 23.1558 11.9084 22.7348 12.2856C22.3138 12.6623 22.2766 13.3096 22.6537 13.7311C22.9377 14.0489 24.3987 15.6569 25.2768 16.1201C25.649 16.3164 26.0017 16.4146 26.3329 16.4146C26.5181 16.4146 26.6968 16.3835 26.8676 16.3219C27.567 16.0673 27.8271 15.4272 28.0007 15.0035C28.0207 14.9536 28.0463 14.892 28.0712 14.8343C28.1804 14.8837 28.3169 14.9558 28.4201 15.0112C28.781 15.2039 29.3185 15.49 29.9431 15.5274C29.9484 15.6848 29.9521 15.8427 29.9521 16.0014C29.9521 18.2559 29.4139 20.3869 28.4602 22.2736C28.0809 21.9703 27.4988 21.6921 26.6201 21.6462C25.7104 21.593 24.0509 21.9857 23.1513 25.1334C22.9959 25.6764 23.311 26.2439 23.8546 26.3992C23.9483 26.4264 24.0437 26.4391 24.1369 26.4391C24.5818 26.4391 24.9916 26.1457 25.1203 25.6964C25.4819 24.434 26.0034 23.6575 26.5126 23.6913C27.0229 23.7185 27.1832 23.8655 27.2203 23.9099C27.273 23.9732 27.2913 24.0774 27.2948 24.1818C24.757 27.6756 20.6403 29.9522 16.0011 29.9522Z\" fill=\"#8CB93F\"><\/path><\/g><defs><clipPath id=\"clip0_32_123\"><rect width=\"32\" height=\"32\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t10+\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCountries\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2359c87 elementor-widget elementor-widget-spacer\" data-id=\"2359c87\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3a2f3e elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"f3a2f3e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/biocure-bd.com\/index.php\/about\/\" id=\"about-learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#043252\" stroke=\"#043252\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8bcee23 e-flex e-con-boxed e-con e-parent\" data-id=\"8bcee23\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-030e0f0 elementor-widget elementor-widget-heading\" data-id=\"030e0f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Product Categories<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-692d46d elementor-widget elementor-widget-spacer\" data-id=\"692d46d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47d744b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"47d744b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Comprehensive range of pharmaceutical products across multiple therapeutic areas<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bd277d elementor-widget elementor-widget-spacer\" data-id=\"1bd277d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b915d20 elementor-arrows-position-inside elementor-widget elementor-widget-n-carousel\" data-id=\"b915d20\" data-element_type=\"widget\" id=\"category-card\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;af508f1&quot;},{&quot;slide_title&quot;:&quot;Slide #2&quot;,&quot;_id&quot;:&quot;59a1f65&quot;},{&quot;slide_title&quot;:&quot;Slide #3&quot;,&quot;_id&quot;:&quot;cb5e60f&quot;},{&quot;slide_title&quot;:&quot;Slide #4&quot;,&quot;_id&quot;:&quot;7ca6bb8&quot;},{&quot;slide_title&quot;:&quot;Slide #5&quot;,&quot;_id&quot;:&quot;c2eff38&quot;},{&quot;slide_title&quot;:&quot;Slide #6&quot;,&quot;_id&quot;:&quot;a54b0dd&quot;}],&quot;slides_to_show&quot;:&quot;4&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:24,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47922cc e-flex e-con-boxed e-con e-child\" data-id=\"47922cc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cb7a247 e-con-full e-flex e-con e-child\" data-id=\"cb7a247\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-faf7bb0 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"faf7bb0\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M31.6667 18.3333H8.33333M31.6667 18.3333C32.5507 18.3333 33.3986 18.6845 34.0237 19.3096C34.6488 19.9348 35 20.7826 35 21.6667V31.6667C35 32.5507 34.6488 33.3986 34.0237 34.0237C33.3986 34.6488 32.5507 35 31.6667 35H8.33333C7.44928 35 6.60143 34.6488 5.97631 34.0237C5.35119 33.3986 5 32.5507 5 31.6667V21.6667C5 20.7826 5.35119 19.9348 5.97631 19.3096C6.60143 18.6845 7.44928 18.3333 8.33333 18.3333M31.6667 18.3333V15C31.6667 14.1159 31.3155 13.2681 30.6904 12.643C30.0652 12.0179 29.2174 11.6667 28.3333 11.6667M8.33333 18.3333V15C8.33333 14.1159 8.68452 13.2681 9.30964 12.643C9.93477 12.0179 10.7826 11.6667 11.6667 11.6667M28.3333 11.6667V8.33333C28.3333 7.44928 27.9821 6.60143 27.357 5.97631C26.7319 5.35119 25.8841 5 25 5H15C14.1159 5 13.2681 5.35119 12.643 5.97631C12.0179 6.60143 11.6667 7.44928 11.6667 8.33333V11.6667M28.3333 11.6667H11.6667\" stroke=\"#2563EB\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-749aeef elementor-widget elementor-widget-spacer\" data-id=\"749aeef\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99ed327 elementor-widget elementor-widget-heading\" data-id=\"99ed327\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Neuromedicine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-323ab6e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"323ab6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Brain and nervous system health.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa68964 elementor-tablet-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"aa68964\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\" id=\"about-learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea8f6ef e-flex e-con-boxed e-con e-child\" data-id=\"ea8f6ef\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f2f8da8 e-con-full e-flex e-con e-child\" data-id=\"f2f8da8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb4cd99 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"eb4cd99\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M31.6667 18.3333H8.33333M31.6667 18.3333C32.5507 18.3333 33.3986 18.6845 34.0237 19.3096C34.6488 19.9348 35 20.7826 35 21.6667V31.6667C35 32.5507 34.6488 33.3986 34.0237 34.0237C33.3986 34.6488 32.5507 35 31.6667 35H8.33333C7.44928 35 6.60143 34.6488 5.97631 34.0237C5.35119 33.3986 5 32.5507 5 31.6667V21.6667C5 20.7826 5.35119 19.9348 5.97631 19.3096C6.60143 18.6845 7.44928 18.3333 8.33333 18.3333M31.6667 18.3333V15C31.6667 14.1159 31.3155 13.2681 30.6904 12.643C30.0652 12.0179 29.2174 11.6667 28.3333 11.6667M8.33333 18.3333V15C8.33333 14.1159 8.68452 13.2681 9.30964 12.643C9.93477 12.0179 10.7826 11.6667 11.6667 11.6667M28.3333 11.6667V8.33333C28.3333 7.44928 27.9821 6.60143 27.357 5.97631C26.7319 5.35119 25.8841 5 25 5H15C14.1159 5 13.2681 5.35119 12.643 5.97631C12.0179 6.60143 11.6667 7.44928 11.6667 8.33333V11.6667M28.3333 11.6667H11.6667\" stroke=\"#2563EB\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4e0356 elementor-widget elementor-widget-spacer\" data-id=\"b4e0356\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2428fcf elementor-widget elementor-widget-heading\" data-id=\"2428fcf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nephrology<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35ae5f4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"35ae5f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Kidney function and disease care.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86279d2 elementor-tablet-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"86279d2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\" id=\"about-learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77f239b e-flex e-con-boxed e-con e-child\" data-id=\"77f239b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-83450e0 e-con-full e-flex e-con e-child\" data-id=\"83450e0\" data-element_type=\"container\" href=\"https:\/\/biocure-bd.com\/index.php\/products-category\/hematology\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8549ef2 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8549ef2\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M31.6667 18.3333H8.33333M31.6667 18.3333C32.5507 18.3333 33.3986 18.6845 34.0237 19.3096C34.6488 19.9348 35 20.7826 35 21.6667V31.6667C35 32.5507 34.6488 33.3986 34.0237 34.0237C33.3986 34.6488 32.5507 35 31.6667 35H8.33333C7.44928 35 6.60143 34.6488 5.97631 34.0237C5.35119 33.3986 5 32.5507 5 31.6667V21.6667C5 20.7826 5.35119 19.9348 5.97631 19.3096C6.60143 18.6845 7.44928 18.3333 8.33333 18.3333M31.6667 18.3333V15C31.6667 14.1159 31.3155 13.2681 30.6904 12.643C30.0652 12.0179 29.2174 11.6667 28.3333 11.6667M8.33333 18.3333V15C8.33333 14.1159 8.68452 13.2681 9.30964 12.643C9.93477 12.0179 10.7826 11.6667 11.6667 11.6667M28.3333 11.6667V8.33333C28.3333 7.44928 27.9821 6.60143 27.357 5.97631C26.7319 5.35119 25.8841 5 25 5H15C14.1159 5 13.2681 5.35119 12.643 5.97631C12.0179 6.60143 11.6667 7.44928 11.6667 8.33333V11.6667M28.3333 11.6667H11.6667\" stroke=\"#2563EB\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-207c3ba elementor-widget elementor-widget-spacer\" data-id=\"207c3ba\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e163028 elementor-widget elementor-widget-heading\" data-id=\"e163028\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hematology<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17fe0fa elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"17fe0fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Blood disorders and related conditions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeeb3eb elementor-tablet-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"aeeb3eb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/biocure-bd.com\/index.php\/products-category\/hematology\/\" id=\"about-learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96c6817 e-flex e-con-boxed e-con e-child\" data-id=\"96c6817\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-f4fffeb e-con-full e-flex e-con e-child\" data-id=\"f4fffeb\" data-element_type=\"container\" href=\"https:\/\/biocure-bd.com\/index.php\/products-category\/oncology\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8e6a5 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ee8e6a5\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M31.6667 18.3333H8.33333M31.6667 18.3333C32.5507 18.3333 33.3986 18.6845 34.0237 19.3096C34.6488 19.9348 35 20.7826 35 21.6667V31.6667C35 32.5507 34.6488 33.3986 34.0237 34.0237C33.3986 34.6488 32.5507 35 31.6667 35H8.33333C7.44928 35 6.60143 34.6488 5.97631 34.0237C5.35119 33.3986 5 32.5507 5 31.6667V21.6667C5 20.7826 5.35119 19.9348 5.97631 19.3096C6.60143 18.6845 7.44928 18.3333 8.33333 18.3333M31.6667 18.3333V15C31.6667 14.1159 31.3155 13.2681 30.6904 12.643C30.0652 12.0179 29.2174 11.6667 28.3333 11.6667M8.33333 18.3333V15C8.33333 14.1159 8.68452 13.2681 9.30964 12.643C9.93477 12.0179 10.7826 11.6667 11.6667 11.6667M28.3333 11.6667V8.33333C28.3333 7.44928 27.9821 6.60143 27.357 5.97631C26.7319 5.35119 25.8841 5 25 5H15C14.1159 5 13.2681 5.35119 12.643 5.97631C12.0179 6.60143 11.6667 7.44928 11.6667 8.33333V11.6667M28.3333 11.6667H11.6667\" stroke=\"#2563EB\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b16704 elementor-widget elementor-widget-spacer\" data-id=\"5b16704\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-433477e elementor-widget elementor-widget-heading\" data-id=\"433477e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Oncology<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd843f8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"dd843f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Cancer diagnosis and treatment.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-499481a elementor-tablet-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"499481a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/biocure-bd.com\/index.php\/products-category\/oncology\/\" id=\"about-learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fa9fe9 e-flex e-con-boxed e-con e-child\" data-id=\"0fa9fe9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0b06698 e-con-full e-flex e-con e-child\" data-id=\"0b06698\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-502f6fb elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"502f6fb\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M31.6667 18.3333H8.33333M31.6667 18.3333C32.5507 18.3333 33.3986 18.6845 34.0237 19.3096C34.6488 19.9348 35 20.7826 35 21.6667V31.6667C35 32.5507 34.6488 33.3986 34.0237 34.0237C33.3986 34.6488 32.5507 35 31.6667 35H8.33333C7.44928 35 6.60143 34.6488 5.97631 34.0237C5.35119 33.3986 5 32.5507 5 31.6667V21.6667C5 20.7826 5.35119 19.9348 5.97631 19.3096C6.60143 18.6845 7.44928 18.3333 8.33333 18.3333M31.6667 18.3333V15C31.6667 14.1159 31.3155 13.2681 30.6904 12.643C30.0652 12.0179 29.2174 11.6667 28.3333 11.6667M8.33333 18.3333V15C8.33333 14.1159 8.68452 13.2681 9.30964 12.643C9.93477 12.0179 10.7826 11.6667 11.6667 11.6667M28.3333 11.6667V8.33333C28.3333 7.44928 27.9821 6.60143 27.357 5.97631C26.7319 5.35119 25.8841 5 25 5H15C14.1159 5 13.2681 5.35119 12.643 5.97631C12.0179 6.60143 11.6667 7.44928 11.6667 8.33333V11.6667M28.3333 11.6667H11.6667\" stroke=\"#2563EB\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d88f950 elementor-widget elementor-widget-spacer\" data-id=\"d88f950\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c70b129 elementor-widget elementor-widget-heading\" data-id=\"c70b129\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hepatitis &amp; Virology<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-838d353 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"838d353\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Viral infections, especially liver-related.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee0dc35 elementor-tablet-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ee0dc35\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\" id=\"about-learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a884f92 e-flex e-con-boxed e-con e-child\" data-id=\"a884f92\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a88ca60 e-con-full e-flex e-con e-child\" data-id=\"a88ca60\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b46d8d elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5b46d8d\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M31.6667 18.3333H8.33333M31.6667 18.3333C32.5507 18.3333 33.3986 18.6845 34.0237 19.3096C34.6488 19.9348 35 20.7826 35 21.6667V31.6667C35 32.5507 34.6488 33.3986 34.0237 34.0237C33.3986 34.6488 32.5507 35 31.6667 35H8.33333C7.44928 35 6.60143 34.6488 5.97631 34.0237C5.35119 33.3986 5 32.5507 5 31.6667V21.6667C5 20.7826 5.35119 19.9348 5.97631 19.3096C6.60143 18.6845 7.44928 18.3333 8.33333 18.3333M31.6667 18.3333V15C31.6667 14.1159 31.3155 13.2681 30.6904 12.643C30.0652 12.0179 29.2174 11.6667 28.3333 11.6667M8.33333 18.3333V15C8.33333 14.1159 8.68452 13.2681 9.30964 12.643C9.93477 12.0179 10.7826 11.6667 11.6667 11.6667M28.3333 11.6667V8.33333C28.3333 7.44928 27.9821 6.60143 27.357 5.97631C26.7319 5.35119 25.8841 5 25 5H15C14.1159 5 13.2681 5.35119 12.643 5.97631C12.0179 6.60143 11.6667 7.44928 11.6667 8.33333V11.6667M28.3333 11.6667H11.6667\" stroke=\"#2563EB\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2e5520 elementor-widget elementor-widget-spacer\" data-id=\"f2e5520\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13060d7 elementor-widget elementor-widget-heading\" data-id=\"13060d7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cardiovascular<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dce17f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1dce17f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Heart and blood vessel health.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d211cfb elementor-tablet-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d211cfb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\" id=\"about-learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"15\" viewBox=\"0 0 18 15\" fill=\"none\"><path d=\"M16.6291 6.51668C16.705 6.59251 16.7649 6.68278 16.8059 6.78184C16.847 6.88097 16.8688 6.98736 16.8688 7.09466C16.8688 7.20195 16.847 7.30834 16.8059 7.40747C16.7649 7.50653 16.705 7.59681 16.6291 7.67263C16.5533 7.74845 16.463 7.80835 16.364 7.84941C16.2649 7.89046 16.1584 7.91224 16.0512 7.91225L2.93793 7.91087L7.67223 12.6452C7.82531 12.7983 7.91108 13.006 7.91115 13.2225C7.91115 13.4389 7.82523 13.6466 7.67223 13.7997C7.51908 13.9529 7.31084 14.0394 7.09425 14.0394C6.87783 14.0392 6.67 13.9535 6.51696 13.8004L0.389167 7.67263C0.236016 7.51948 0.149552 7.31124 0.149551 7.09466C0.149551 6.87807 0.236016 6.66983 0.389167 6.51668L6.51696 0.388881C6.67 0.235841 6.87783 0.150081 7.09425 0.149956C7.31084 0.149956 7.51908 0.236421 7.67223 0.389572C7.82523 0.542699 7.91115 0.750386 7.91115 0.966858C7.91108 1.18335 7.82532 1.39106 7.67223 1.54414L2.93862 6.27775L16.0512 6.27706C16.1584 6.27707 16.2649 6.29885 16.364 6.3399C16.463 6.38096 16.5533 6.44086 16.6291 6.51668Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"15\" viewBox=\"0 0 18 15\" fill=\"none\"><path d=\"M0.389014 7.67265C0.313192 7.59683 0.253292 7.50655 0.212237 7.40749C0.171178 7.30836 0.149399 7.20197 0.149399 7.09467C0.149399 6.98738 0.171179 6.88099 0.212237 6.78186C0.253291 6.6828 0.313191 6.59253 0.389014 6.5167C0.464834 6.44088 0.555128 6.38098 0.654179 6.33992C0.753293 6.29887 0.85971 6.27709 0.966991 6.27708L14.0802 6.27846L9.34593 1.54416C9.19284 1.39108 9.10708 1.18337 9.10701 0.966877C9.10701 0.750404 9.19293 0.542717 9.34593 0.38959C9.49908 0.23644 9.70732 0.149975 9.92391 0.149975C10.1403 0.1501 10.3482 0.23586 10.5012 0.3889L16.629 6.5167C16.7821 6.66985 16.8686 6.87809 16.8686 7.09467C16.8686 7.31126 16.7821 7.5195 16.629 7.67265L10.5012 13.8005C10.3482 13.9535 10.1403 14.0392 9.92391 14.0394C9.70732 14.0394 9.49908 13.9529 9.34593 13.7998C9.19293 13.6466 9.10701 13.4389 9.10701 13.2225C9.10708 13.006 9.19284 12.7983 9.34593 12.6452L14.0795 7.91158L0.966991 7.91227C0.859711 7.91226 0.753293 7.89048 0.654179 7.84943C0.555127 7.80837 0.464834 7.74847 0.389014 7.67265Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b40f535 e-flex e-con-boxed e-con e-parent\" data-id=\"b40f535\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7cb6b3b elementor-widget elementor-widget-spacer\" data-id=\"7cb6b3b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f80d40 elementor-widget elementor-widget-heading\" data-id=\"4f80d40\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Featured Products<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fe005d elementor-widget elementor-widget-spacer\" data-id=\"0fe005d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-556659e elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"556659e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Innovative and high-quality medicines for a range of medical needs, including advanced anti-infectives and oncology treatments.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c861b54 elementor-widget elementor-widget-spacer\" data-id=\"c861b54\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1740ff4 e-flex e-con-boxed e-con e-parent\" data-id=\"1740ff4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-078d4cc e-con-full e-flex e-con e-child\" data-id=\"078d4cc\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e882654 e-con-full e-flex e-con e-child\" data-id=\"e882654\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b83c26a e-con-full e-flex e-con e-child\" data-id=\"b83c26a\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9845d66 e-con-full e-flex e-con e-child\" data-id=\"9845d66\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2223255 e-con-full e-flex e-con e-child\" data-id=\"2223255\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1365ab elementor-widget elementor-widget-heading\" data-id=\"e1365ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tablet XYZ 20<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d182202 elementor-widget elementor-widget-heading\" data-id=\"d182202\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prednisolone 20mg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-936ed34 e-con-full e-flex e-con e-child\" data-id=\"936ed34\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e8b8b9 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8e8b8b9\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M22 0C23.1046 0 24 0.89543 24 2V20C24 21.1046 23.1046 22 22 22C20.8954 22 20 21.1046 20 20V6.82812L3.41406 23.4141C2.63302 24.1951 1.36699 24.1951 0.585939 23.4141C-0.195109 22.633 -0.19511 21.367 0.585939 20.5859L17.1719 4H4C2.89543 4 2 3.10457 2 2C2 0.895431 2.89543 3.22127e-07 4 0H22Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e89ae9f e-con-full e-flex e-con e-child\" data-id=\"e89ae9f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dd9ff0d e-con-full e-flex e-con e-child\" data-id=\"dd9ff0d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c46075a e-con-full e-flex e-con e-child\" data-id=\"c46075a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c25cb80 elementor-widget elementor-widget-image\" data-id=\"c25cb80\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav.png\" class=\"attachment-large size-large wp-image-1288\" alt=\"\" srcset=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav.png 512w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-300x300.png 300w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-150x150.png 150w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-160x160.png 160w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98c4b6b e-con-full e-flex e-con e-child\" data-id=\"98c4b6b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ad9481e e-con-full e-flex e-con e-child\" data-id=\"ad9481e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0926e07 elementor-widget elementor-widget-heading\" data-id=\"0926e07\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tablet XYZ 20<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb0f33 elementor-widget elementor-widget-heading\" data-id=\"3fb0f33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prednisolone 20mg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed54d9b e-con-full e-flex e-con e-child\" data-id=\"ed54d9b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-106a3b8 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"106a3b8\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#043252\" stroke=\"#043252\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7561c00 e-con-full e-flex e-con e-child\" data-id=\"7561c00\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a70c8f5 elementor-widget elementor-widget-image\" data-id=\"a70c8f5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav.png\" class=\"attachment-large size-large wp-image-1288\" alt=\"\" srcset=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav.png 512w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-300x300.png 300w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-150x150.png 150w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-160x160.png 160w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31f2d3c e-con-full e-flex e-con e-child\" data-id=\"31f2d3c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ba4762e e-con-full e-flex e-con e-child\" data-id=\"ba4762e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c48846 elementor-widget elementor-widget-heading\" data-id=\"3c48846\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tablet XYZ 20<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edb62ed elementor-widget elementor-widget-heading\" data-id=\"edb62ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prednisolone 20mg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cb3261 e-con-full e-flex e-con e-child\" data-id=\"5cb3261\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca71725 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ca71725\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#043252\" stroke=\"#043252\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a3026a elementor-widget elementor-widget-spacer\" data-id=\"7a3026a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8e220c e-con-full e-flex e-con e-child\" data-id=\"d8e220c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-db12b9c e-con-full e-flex e-con e-child\" data-id=\"db12b9c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-556f18f elementor-widget elementor-widget-image\" data-id=\"556f18f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav.png\" class=\"attachment-full size-full wp-image-1288\" alt=\"\" srcset=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav.png 512w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-300x300.png 300w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-150x150.png 150w, https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/11\/BioCure_Fav-160x160.png 160w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50bc5fb e-con-full e-flex e-con e-child\" data-id=\"50bc5fb\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7fae58f e-con-full e-flex e-con e-child\" data-id=\"7fae58f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc6a51c elementor-widget elementor-widget-heading\" data-id=\"cc6a51c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ZXY<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-904a7e4 elementor-widget elementor-widget-heading\" data-id=\"904a7e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">XYZ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-002a4cb e-con-full e-flex e-con e-child\" data-id=\"002a4cb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f398d1 elementor-tablet-align-left elementor-widget elementor-widget-button\" data-id=\"1f398d1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/biocure-bd.com\/index.php\/products\/pembromax\/\" id=\"about-learn-btn\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M1.05042 13.9508C0.932171 13.9508 0.814932 13.9267 0.705688 13.8815C0.596644 13.8363 0.497195 13.7706 0.413696 13.6871C0.330083 13.6035 0.263634 13.5034 0.218384 13.3942C0.173297 13.2852 0.150079 13.1684 0.150024 13.0504C0.150024 12.9323 0.17321 12.8149 0.218384 12.7057C0.263596 12.5965 0.330182 12.4973 0.413696 12.4137L10.8785 1.94983H3.30042C3.06172 1.94983 2.83248 1.85494 2.6637 1.68616C2.49519 1.5175 2.40013 1.28883 2.40002 1.05042C2.40002 0.811819 2.49504 0.58246 2.6637 0.413696C2.83248 0.244913 3.06172 0.150024 3.30042 0.150024H13.0504C13.2891 0.150024 13.5184 0.244913 13.6871 0.413696C13.8558 0.582459 13.9508 0.811818 13.9508 1.05042V10.8004C13.9507 11.0388 13.8556 11.2675 13.6871 11.4362C13.5184 11.6049 13.2891 11.6998 13.0504 11.6998C12.8117 11.6998 12.5825 11.6049 12.4137 11.4362C12.2452 11.2675 12.1501 11.0388 12.15 10.8004V3.22424L1.68713 13.6871C1.60364 13.7706 1.50419 13.8363 1.39514 13.8815C1.2859 13.9267 1.16866 13.9508 1.05042 13.9508Z\" fill=\"#0A72BA\" stroke=\"#0A72BA\" stroke-width=\"0.3\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49cf9f4 e-con-full e-flex e-con e-child\" data-id=\"49cf9f4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ce9c0f elementor-widget__width-initial elementor-widget elementor-widget-video\" data-id=\"0ce9c0f\" data-element_type=\"widget\" id=\"product-video\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/10\/product-thumb-video-FINAL.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlsList=\"nodownload\" poster=\"https:\/\/biocure-bd.com\/wp-content\/uploads\/2025\/10\/prdoducts-thumb.jpg\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e506f1 e-flex e-con-boxed e-con e-parent\" data-id=\"9e506f1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-810cb5f elementor-widget elementor-widget-spacer\" data-id=\"810cb5f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>The Science of Wellness, Realized. Learn More BIOCURE The Science ofWellness, Realized. Learn More BIOCURE The Science ofWellness, Realized. Learn [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-12","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/biocure-bd.com\/index.php\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biocure-bd.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biocure-bd.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biocure-bd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biocure-bd.com\/index.php\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":54,"href":"https:\/\/biocure-bd.com\/index.php\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":2513,"href":"https:\/\/biocure-bd.com\/index.php\/wp-json\/wp\/v2\/pages\/12\/revisions\/2513"}],"wp:attachment":[{"href":"https:\/\/biocure-bd.com\/index.php\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}